{"id":44,"count":2,"description":"","link":"https:\/\/vitalitycenterjax.com\/es\/tag\/prenatal-wellness\/","name":"Bienestar prenatal","slug":"bienestar-prenatal","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.7 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Prenatal Wellness Archives - Vitality Center Jacksonville<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vitalitycenterjax.com\/es\/etiqueta\/bienestar-prenatal\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prenatal Wellness Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vitalitycenterjax.com\/es\/etiqueta\/bienestar-prenatal\/\" \/>\n<meta property=\"og:site_name\" content=\"Vitality Center Jacksonville\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vitalitycenterjax.com\/wp-content\/uploads\/2018\/09\/cropped-vfc-circle-1200x1200-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/vitalitycenterjax.com\\\/tag\\\/prenatal-wellness\\\/\",\"url\":\"https:\\\/\\\/vitalitycenterjax.com\\\/tag\\\/prenatal-wellness\\\/\",\"name\":\"Prenatal Wellness Archives - Vitality Center Jacksonville\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vitalitycenterjax.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vitalitycenterjax.com\\\/tag\\\/prenatal-wellness\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vitalitycenterjax.com\\\/tag\\\/prenatal-wellness\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/vitalitycenterjax.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prenatal Wellness\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/vitalitycenterjax.com\\\/#website\",\"url\":\"http:\\\/\\\/vitalitycenterjax.com\\\/\",\"name\":\"Vitality Center Jacksonville\",\"description\":\"Quality Chiropractic Care and Healthcare Options\",\"publisher\":{\"@id\":\"http:\\\/\\\/vitalitycenterjax.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/vitalitycenterjax.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Organization\",\"Place\",\"MedicalClinic\"],\"@id\":\"http:\\\/\\\/vitalitycenterjax.com\\\/#organization\",\"name\":\"Vitality Center Jacksonville\",\"url\":\"http:\\\/\\\/vitalitycenterjax.com\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/vitalitycenterjax.com\\\/tag\\\/prenatal-wellness\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/vitalitycenterjax.com\\\/tag\\\/prenatal-wellness\\\/#local-main-organization-logo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/vitalitycenterjax\",\"https:\\\/\\\/www.instagram.com\\\/vitalitycenterjax\\\/\"],\"address\":{\"@id\":\"https:\\\/\\\/vitalitycenterjax.com\\\/tag\\\/prenatal-wellness\\\/#local-main-place-address\"},\"telephone\":[\"(904) 434-3465\"],\"contactPoint\":{\"@type\":\"ContactPoint\",\"telephone\":\"(904) 434-3465\",\"email\":\"frontdesk@vitalitycenterjax.com\"},\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Thursday\"],\"opens\":\"09:00\",\"closes\":\"18:30\"},{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Tuesday\",\"Wednesday\"],\"opens\":\"08:30\",\"closes\":\"17:00\"},{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"00:00\",\"closes\":\"00:00\"}],\"email\":\"frontdesk@vitalitycenterjax.com\",\"areaServed\":\"Jacksonville\",\"priceRange\":\"$\",\"currenciesAccepted\":\"USD\"},{\"@type\":\"PostalAddress\",\"@id\":\"https:\\\/\\\/vitalitycenterjax.com\\\/tag\\\/prenatal-wellness\\\/#local-main-place-address\",\"streetAddress\":\"3636 University Blvd S Suite B3\",\"addressLocality\":\"Jacksonville\",\"postalCode\":\"32216\",\"addressRegion\":\"FL\",\"addressCountry\":\"US\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vitalitycenterjax.com\\\/tag\\\/prenatal-wellness\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/vitalitycenterjax.com\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/vfc-circle-e1537364957593.png\",\"contentUrl\":\"https:\\\/\\\/vitalitycenterjax.com\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/vfc-circle-e1537364957593.png\",\"width\":855,\"height\":855,\"caption\":\"Vitality Center Jacksonville\"}]}<\/script>\n<meta name=\"geo.placename\" content=\"Jacksonville\" \/>\n<meta name=\"geo.region\" content=\"United States (US)\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Prenatal Wellness Archives - Vitality Center Jacksonville","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vitalitycenterjax.com\/es\/etiqueta\/bienestar-prenatal\/","og_locale":"es_ES","og_type":"article","og_title":"Prenatal Wellness Archives","og_url":"https:\/\/vitalitycenterjax.com\/es\/etiqueta\/bienestar-prenatal\/","og_site_name":"Vitality Center Jacksonville","og_image":[{"width":512,"height":512,"url":"https:\/\/vitalitycenterjax.com\/wp-content\/uploads\/2018\/09\/cropped-vfc-circle-1200x1200-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/vitalitycenterjax.com\/tag\/prenatal-wellness\/","url":"https:\/\/vitalitycenterjax.com\/tag\/prenatal-wellness\/","name":"Archivos de bienestar prenatal - Vitality Center Jacksonville","isPartOf":{"@id":"http:\/\/vitalitycenterjax.com\/#website"},"breadcrumb":{"@id":"https:\/\/vitalitycenterjax.com\/tag\/prenatal-wellness\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/vitalitycenterjax.com\/tag\/prenatal-wellness\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/vitalitycenterjax.com\/"},{"@type":"ListItem","position":2,"name":"Prenatal Wellness"}]},{"@type":"WebSite","@id":"http:\/\/vitalitycenterjax.com\/#website","url":"http:\/\/vitalitycenterjax.com\/","name":"Vitality Center Jacksonville - Espa\u00f1ol","description":"Atenci\u00f3n quiropr\u00e1ctica de calidad y opciones de atenci\u00f3n m\u00e9dica","publisher":{"@id":"http:\/\/vitalitycenterjax.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/vitalitycenterjax.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Organization","Place","MedicalClinic"],"@id":"http:\/\/vitalitycenterjax.com\/#organization","name":"Vitality Center Jacksonville - Espa\u00f1ol","url":"http:\/\/vitalitycenterjax.com\/","logo":{"@id":"https:\/\/vitalitycenterjax.com\/tag\/prenatal-wellness\/#local-main-organization-logo"},"image":{"@id":"https:\/\/vitalitycenterjax.com\/tag\/prenatal-wellness\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/vitalitycenterjax","https:\/\/www.instagram.com\/vitalitycenterjax\/"],"address":{"@id":"https:\/\/vitalitycenterjax.com\/tag\/prenatal-wellness\/#local-main-place-address"},"telephone":["(904) 434-3465"],"contactPoint":{"@type":"ContactPoint","telephone":"(904) 434-3465","email":"frontdesk@vitalitycenterjax.com"},"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Thursday"],"opens":"09:00","closes":"18:30"},{"@type":"OpeningHoursSpecification","dayOfWeek":["Tuesday","Wednesday"],"opens":"08:30","closes":"17:00"},{"@type":"OpeningHoursSpecification","dayOfWeek":["Friday","Saturday","Sunday"],"opens":"00:00","closes":"00:00"}],"email":"frontdesk@vitalitycenterjax.com","areaServed":"Jacksonville","priceRange":"$","currenciesAccepted":"USD"},{"@type":"PostalAddress","@id":"https:\/\/vitalitycenterjax.com\/tag\/prenatal-wellness\/#local-main-place-address","streetAddress":"3636 University Blvd S Suite B3","addressLocality":"Jacksonville","postalCode":"32216","addressRegion":"FL","addressCountry":"US"},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vitalitycenterjax.com\/tag\/prenatal-wellness\/#local-main-organization-logo","url":"https:\/\/vitalitycenterjax.com\/wp-content\/uploads\/2018\/09\/vfc-circle-e1537364957593.png","contentUrl":"https:\/\/vitalitycenterjax.com\/wp-content\/uploads\/2018\/09\/vfc-circle-e1537364957593.png","width":855,"height":855,"caption":"Vitality Center Jacksonville"}]},"geo.placename":"Jacksonville","geo.region":"United States (US)"},"_links":{"self":[{"href":"https:\/\/vitalitycenterjax.com\/es\/wp-json\/wp\/v2\/tags\/44","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vitalitycenterjax.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/vitalitycenterjax.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/vitalitycenterjax.com\/es\/wp-json\/wp\/v2\/posts?tags=44"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}