{"id":1899,"date":"2021-08-31T21:50:12","date_gmt":"2021-08-31T21:50:12","guid":{"rendered":"https:\/\/vitalitycenterjax.com\/?p=1899"},"modified":"2024-04-25T18:56:30","modified_gmt":"2024-04-25T18:56:30","slug":"como-reducir-el-dolor-de-espalda-durante-el-embarazo-y-trabajando-desde-casa","status":"publish","type":"post","link":"https:\/\/vitalitycenterjax.com\/es\/how-to-reduce-back-pain-while-pregnant-and-working-from-home\/","title":{"rendered":"C\u00f3mo reducir el dolor de espalda durante el embarazo y trabajar desde casa"},"content":{"rendered":"<p>En muchos sentidos, la repentina ubicuidad del trabajo remoto resulta beneficiosa para las personas embarazadas. Para muchas familias embarazadas, la posibilidad de quedarse en casa y al mismo tiempo mantenerse productivos es un punto de inflexi\u00f3n absoluto. Gracias a que muchas empresas ofrecen (o exigen) este estilo de trabajo durante la pandemia, los futuros padres pueden moderar su riesgo a un nivel que les resulte c\u00f3modo.<\/p>\n<p>Sin embargo, trabajar desde casa tiene desventajas, especialmente cuando se trata de <a href=\"https:\/\/londonlovesbusiness.com\/remote-work-leading-to-increase-in-back-pain-survey-shows\/\">salud espinal<\/a>. El embarazo ya es conocido por provocar dolores de espalda y molestias musculares. Sin embargo, cuando trabaja desde casa, es mucho m\u00e1s probable que sea menos activo y menos m\u00f3vil. Esto, combinado con una oficina en casa no ergon\u00f3mica, puede provocar graves problemas de espalda que persisten durante y despu\u00e9s del embarazo.<\/p>\n<p><a href=\"https:\/\/vitalitycenterjax.com\/es\/\">Quiropr\u00e1ctica familiar de vitalidad <\/a>\u00a0ayuda a las mujeres embarazadas a cuidarse lo mejor posible durante el embarazo. Con ese fin, hemos elaborado esta gu\u00eda para ayudarle a descubrir c\u00f3mo proteger y fortalecer su espalda mientras trabaja de forma remota:<\/p>\n<p><strong><em><u>Reduce el estres <\/u><\/em><\/strong><\/p>\n<p>El embarazo es estresante, las pandemias son estresantes y, de repente, trabajar en un entorno nuevo es estresante. Basta decir que probablemente est\u00e9 sufriendo estr\u00e9s en casi todas las direcciones en este momento, especialmente si desempe\u00f1a un papel de liderazgo en su trabajo. <a href=\"https:\/\/www.zenbusiness.com\/blog\/the-stress-of-being-a-manager\/\">ZenNegocios<\/a> se\u00f1ala que cuantos m\u00e1s empleados supervise, mayores ser\u00e1n los niveles de estr\u00e9s, y mantener un equilibrio adecuado entre el trabajo y la vida personal es uno de los mayores factores estresantes de todos. Aunque sentir cierta ansiedad por todo esto es perfectamente normal, tambi\u00e9n puede provocar un efecto bola de nieve.<\/p>\n<p>El estr\u00e9s tiende a tensar los m\u00fasculos, lo que puede provocar una peor postura y, como resultado, <a href=\"https:\/\/www.laspine.com\/stress-relief-for-back-pain\/\">m\u00e1s dolor de espalda<\/a>. Adem\u00e1s, cuando est\u00e1s estresado, a menudo terminas fatigado y desmotivado, lo que hace que sea menos probable que tomes las medidas necesarias para cuidar de ti mismo adecuadamente. Afortunadamente, como se\u00f1ala Healthline, <a href=\"https:\/\/www.healthline.com\/nutrition\/16-ways-relieve-stress-anxiety\">t\u00e9cnicas de reducci\u00f3n del estr\u00e9s<\/a> puede ser de gran ayuda para reducir el dolor y empoderarlo para tomar medidas preventivas.<\/p>\n<p>Por ejemplo, podr\u00edas comenzar una pr\u00e1ctica diaria de yoga durante el embarazo o trabajar en el desarrollo de la atenci\u00f3n plena. Si descubre que tiene muchos problemas para relajarse, deber\u00eda considerar hacer algo para <a href=\"https:\/\/www.redfin.com\/blog\/clearing-bad-energy-from-your-home\/\">reinicia la energ\u00eda de tu hogar<\/a>. Mucho estr\u00e9s en una sola \u00e1rea puede efectivamente crear una asociaci\u00f3n con la ansiedad cuando est\u00e1s en ese espacio. Redecorar, reorganizar o incluso simplemente dejar entrar un poco de aire fresco puede ayudar a redefinir el ambiente de su hogar.<\/p>\n<p><strong><em><u>Priorizar la postura <\/u><\/em><\/strong><\/p>\n<p>Otro paso que puedes tomar para proteger la salud de tu espalda mientras trabajas desde casa es priorizar una buena postura. En un entorno de oficina, la mayor\u00eda de las personas est\u00e1n acostumbradas a utilizar monitores grandes y elevados que facilitan una posici\u00f3n neutral de la cabeza. En casa, sin embargo, muchas personas trabajan con computadoras port\u00e1tiles y, como resultado, pasan m\u00e1s tiempo mirando la pantalla. Esto da como resultado el bien llamado \u201c<a href=\"https:\/\/spineina.com\/blog\/all-about-tech-neck\/\">Cuello de texto<\/a>\u201d, un tipo de mala postura que ejerce una presi\u00f3n innecesaria sobre la espalda. Elevar la pantalla puede contribuir en gran medida a reducir este problema: utilice un teclado externo para levantar su computadora port\u00e1til y trabajar de manera efectiva.<\/p>\n<p>La postura tiene m\u00e1s <a href=\"https:\/\/my.clevelandclinic.org\/health\/articles\/6913-pregnancy-correct-posture--body-mechanics\">impacto en las personas embarazadas<\/a> de lo que te imaginas. Adem\u00e1s de fortalecer el n\u00facleo y reducir el dolor de espalda, una buena postura es vital para una posici\u00f3n fetal \u00f3ptima al final del tercer trimestre. Cuando te sientas derecho y evitas hacer abdominales, abres espacio en el torso y la pelvis, lo que le da al beb\u00e9 espacio para participar correctamente. Esto puede hacer que el trabajo sea m\u00e1s seguro y m\u00e1s f\u00e1cil para todos.<\/p>\n<p><strong><em><u>Caminar diariamente <\/u><\/em><\/strong><\/p>\n<p>Por \u00faltimo, trabajar desde casa tiende a volverte m\u00e1s sedentario. Cuando entras y sales de una oficina, hay muchos momentos de caminata incidental (hacia el auto, hacia tu escritorio, a la sala de descanso) y, aunque pueden parecer peque\u00f1os momentos, a menudo no se replican en el entorno de trabajo remoto.<\/p>\n<p>Como resultado, debes intencionalmente <a href=\"https:\/\/www.momjunction.com\/articles\/amazing-benefits-of-walking-during-pregnancy_00211\/\">aumenta tu caminata<\/a> para compensar esto. Las caminatas diarias mantendr\u00e1n fuerte su n\u00facleo, la ayudar\u00e1n a mantenerse activa y a desarrollar la resistencia necesaria para el parto. Recuerde, se est\u00e1 preparando para un esfuerzo f\u00edsico importante: su cuerpo necesita entrenamiento para poder afrontarlo.<\/p>\n<p>El trabajo remoto ofrece un mundo de beneficios para los futuros padres, pero tambi\u00e9n tiene inconvenientes. Aseg\u00farese de proteger su columna y su n\u00facleo y de hacer mucho ejercicio para mantenerse saludable mientras trabaja de forma remota. Hacerlo har\u00e1 que el embarazo, el parto y el per\u00edodo posterior sean sustancialmente m\u00e1s f\u00e1ciles y c\u00f3modos.<\/p>\n<p>Autor de la foto: <a href=\"https:\/\/www.pexels.com\/photo\/anonymous-pregnant-female-checking-notification-on-cellphone-5425034\/\">Pexels<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>In many ways, the sudden ubiquity of remote work serves pregnant people well. For many expecting families, the ability to stay home while staying productive is an absolute game-changer. Thanks to many companies offering (or requiring) this workstyle during the pandemic, expecting parents can moderate their risk to a level that feels comfortable to them.Leer M\u00e1s<\/p>","protected":false},"author":1,"featured_media":1900,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_joinchat":[],"footnotes":""},"categories":[39],"tags":[],"class_list":["post-1899","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-from-our-dr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.7 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>How to Reduce Back Pain While Pregnant and Working From Home - Vitality Center Jacksonville<\/title>\n<meta name=\"description\" content=\"For many expecting families, the ability to stay home while staying productive is an absolute game-changer.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vitalitycenterjax.com\/es\/como-reducir-el-dolor-de-espalda-durante-el-embarazo-y-trabajando-desde-casa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"How to Reduce Back Pain While Pregnant and Working From Home\" \/>\n<meta property=\"og:description\" content=\"For many expecting families, the ability to stay home while staying productive is an absolute game-changer.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vitalitycenterjax.com\/es\/como-reducir-el-dolor-de-espalda-durante-el-embarazo-y-trabajando-desde-casa\/\" \/>\n<meta property=\"og:site_name\" content=\"Vitality Center Jacksonville\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/vitalitycenterjax\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-31T21:50:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-25T18:56:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vitalitycenterjax.com\/wp-content\/uploads\/2021\/08\/How-to-Reduce-Back-Pain-While-Pregnant-and-Working-From-Home.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"936\" \/>\n\t<meta property=\"og:image:height\" content=\"624\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"juancarlos2023\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"juancarlos2023\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vitalitycenterjax.com\\\/how-to-reduce-back-pain-while-pregnant-and-working-from-home\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vitalitycenterjax.com\\\/how-to-reduce-back-pain-while-pregnant-and-working-from-home\\\/\"},\"author\":{\"name\":\"juancarlos2023\",\"@id\":\"http:\\\/\\\/vitalitycenterjax.com\\\/#\\\/schema\\\/person\\\/ebae3caa1942839bfbb345af0ff4509c\"},\"headline\":\"How to Reduce Back Pain While Pregnant and Working From Home\",\"datePublished\":\"2021-08-31T21:50:12+00:00\",\"dateModified\":\"2024-04-25T18:56:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vitalitycenterjax.com\\\/how-to-reduce-back-pain-while-pregnant-and-working-from-home\\\/\"},\"wordCount\":751,\"commentCount\":0,\"publisher\":{\"@id\":\"http:\\\/\\\/vitalitycenterjax.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vitalitycenterjax.com\\\/how-to-reduce-back-pain-while-pregnant-and-working-from-home\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vitalitycenterjax.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/How-to-Reduce-Back-Pain-While-Pregnant-and-Working-From-Home.jpg\",\"articleSection\":[\"From Our Dr\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vitalitycenterjax.com\\\/how-to-reduce-back-pain-while-pregnant-and-working-from-home\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vitalitycenterjax.com\\\/how-to-reduce-back-pain-while-pregnant-and-working-from-home\\\/\",\"url\":\"https:\\\/\\\/vitalitycenterjax.com\\\/how-to-reduce-back-pain-while-pregnant-and-working-from-home\\\/\",\"name\":\"How to Reduce Back Pain While Pregnant and Working From Home - Vitality Center Jacksonville\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vitalitycenterjax.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vitalitycenterjax.com\\\/how-to-reduce-back-pain-while-pregnant-and-working-from-home\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vitalitycenterjax.com\\\/how-to-reduce-back-pain-while-pregnant-and-working-from-home\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vitalitycenterjax.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/How-to-Reduce-Back-Pain-While-Pregnant-and-Working-From-Home.jpg\",\"datePublished\":\"2021-08-31T21:50:12+00:00\",\"dateModified\":\"2024-04-25T18:56:30+00:00\",\"description\":\"For many expecting families, the ability to stay home while staying productive is an absolute game-changer.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vitalitycenterjax.com\\\/how-to-reduce-back-pain-while-pregnant-and-working-from-home\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vitalitycenterjax.com\\\/how-to-reduce-back-pain-while-pregnant-and-working-from-home\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vitalitycenterjax.com\\\/how-to-reduce-back-pain-while-pregnant-and-working-from-home\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vitalitycenterjax.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/How-to-Reduce-Back-Pain-While-Pregnant-and-Working-From-Home.jpg\",\"contentUrl\":\"https:\\\/\\\/vitalitycenterjax.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/How-to-Reduce-Back-Pain-While-Pregnant-and-Working-From-Home.jpg\",\"width\":936,\"height\":624},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vitalitycenterjax.com\\\/how-to-reduce-back-pain-while-pregnant-and-working-from-home\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/vitalitycenterjax.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"How to Reduce Back Pain While Pregnant and Working From Home\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/vitalitycenterjax.com\\\/#website\",\"url\":\"http:\\\/\\\/vitalitycenterjax.com\\\/\",\"name\":\"Vitality Center Jacksonville\",\"description\":\"Quality Chiropractic Care and Healthcare Options\",\"publisher\":{\"@id\":\"http:\\\/\\\/vitalitycenterjax.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/vitalitycenterjax.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Organization\",\"Place\",\"MedicalClinic\"],\"@id\":\"http:\\\/\\\/vitalitycenterjax.com\\\/#organization\",\"name\":\"Vitality Center Jacksonville\",\"url\":\"http:\\\/\\\/vitalitycenterjax.com\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/vitalitycenterjax.com\\\/how-to-reduce-back-pain-while-pregnant-and-working-from-home\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/vitalitycenterjax.com\\\/how-to-reduce-back-pain-while-pregnant-and-working-from-home\\\/#local-main-organization-logo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/vitalitycenterjax\",\"https:\\\/\\\/www.instagram.com\\\/vitalitycenterjax\\\/\"],\"address\":{\"@id\":\"https:\\\/\\\/vitalitycenterjax.com\\\/how-to-reduce-back-pain-while-pregnant-and-working-from-home\\\/#local-main-place-address\"},\"telephone\":[\"(904) 434-3465\"],\"contactPoint\":{\"@type\":\"ContactPoint\",\"telephone\":\"(904) 434-3465\",\"email\":\"frontdesk@vitalitycenterjax.com\"},\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Thursday\"],\"opens\":\"09:00\",\"closes\":\"18:30\"},{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Tuesday\",\"Wednesday\"],\"opens\":\"08:30\",\"closes\":\"17:00\"},{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"00:00\",\"closes\":\"00:00\"}],\"email\":\"frontdesk@vitalitycenterjax.com\",\"areaServed\":\"Jacksonville\",\"priceRange\":\"$\",\"currenciesAccepted\":\"USD\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/vitalitycenterjax.com\\\/#\\\/schema\\\/person\\\/ebae3caa1942839bfbb345af0ff4509c\",\"name\":\"juancarlos2023\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/70256e7fa5cde90b9afe5c8505cc59bdcb61e4f24d3c2bd2a6ec18c756d5fff1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/70256e7fa5cde90b9afe5c8505cc59bdcb61e4f24d3c2bd2a6ec18c756d5fff1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/70256e7fa5cde90b9afe5c8505cc59bdcb61e4f24d3c2bd2a6ec18c756d5fff1?s=96&d=mm&r=g\",\"caption\":\"juancarlos2023\"},\"url\":\"https:\\\/\\\/vitalitycenterjax.com\\\/es\\\/author\\\/juancarlos2023\\\/\"},{\"@type\":\"PostalAddress\",\"@id\":\"https:\\\/\\\/vitalitycenterjax.com\\\/how-to-reduce-back-pain-while-pregnant-and-working-from-home\\\/#local-main-place-address\",\"streetAddress\":\"3636 University Blvd S Suite B3\",\"addressLocality\":\"Jacksonville\",\"postalCode\":\"32216\",\"addressRegion\":\"FL\",\"addressCountry\":\"US\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vitalitycenterjax.com\\\/how-to-reduce-back-pain-while-pregnant-and-working-from-home\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/vitalitycenterjax.com\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/vfc-circle-e1537364957593.png\",\"contentUrl\":\"https:\\\/\\\/vitalitycenterjax.com\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/vfc-circle-e1537364957593.png\",\"width\":855,\"height\":855,\"caption\":\"Vitality Center Jacksonville\"}]}<\/script>\n<meta name=\"geo.placename\" content=\"Jacksonville\" \/>\n<meta name=\"geo.region\" content=\"United States (US)\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"C\u00f3mo reducir el dolor de espalda durante el embarazo y trabajar desde casa - Vitality Center Jacksonville","description":"Para muchas familias embarazadas, la posibilidad de quedarse en casa y al mismo tiempo mantenerse productivos es un punto de inflexi\u00f3n absoluto.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vitalitycenterjax.com\/es\/como-reducir-el-dolor-de-espalda-durante-el-embarazo-y-trabajando-desde-casa\/","og_locale":"es_ES","og_type":"article","og_title":"How to Reduce Back Pain While Pregnant and Working From Home","og_description":"For many expecting families, the ability to stay home while staying productive is an absolute game-changer.","og_url":"https:\/\/vitalitycenterjax.com\/es\/como-reducir-el-dolor-de-espalda-durante-el-embarazo-y-trabajando-desde-casa\/","og_site_name":"Vitality Center Jacksonville","article_publisher":"https:\/\/www.facebook.com\/vitalitycenterjax","article_published_time":"2021-08-31T21:50:12+00:00","article_modified_time":"2024-04-25T18:56:30+00:00","og_image":[{"width":936,"height":624,"url":"https:\/\/vitalitycenterjax.com\/wp-content\/uploads\/2021\/08\/How-to-Reduce-Back-Pain-While-Pregnant-and-Working-From-Home.jpg","type":"image\/jpeg"}],"author":"juancarlos2023","twitter_card":"summary_large_image","twitter_misc":{"Written by":"juancarlos2023","Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vitalitycenterjax.com\/how-to-reduce-back-pain-while-pregnant-and-working-from-home\/#article","isPartOf":{"@id":"https:\/\/vitalitycenterjax.com\/how-to-reduce-back-pain-while-pregnant-and-working-from-home\/"},"author":{"name":"juancarlos2023","@id":"http:\/\/vitalitycenterjax.com\/#\/schema\/person\/ebae3caa1942839bfbb345af0ff4509c"},"headline":"How to Reduce Back Pain While Pregnant and Working From Home","datePublished":"2021-08-31T21:50:12+00:00","dateModified":"2024-04-25T18:56:30+00:00","mainEntityOfPage":{"@id":"https:\/\/vitalitycenterjax.com\/how-to-reduce-back-pain-while-pregnant-and-working-from-home\/"},"wordCount":751,"commentCount":0,"publisher":{"@id":"http:\/\/vitalitycenterjax.com\/#organization"},"image":{"@id":"https:\/\/vitalitycenterjax.com\/how-to-reduce-back-pain-while-pregnant-and-working-from-home\/#primaryimage"},"thumbnailUrl":"https:\/\/vitalitycenterjax.com\/wp-content\/uploads\/2021\/08\/How-to-Reduce-Back-Pain-While-Pregnant-and-Working-From-Home.jpg","articleSection":["From Our Dr"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vitalitycenterjax.com\/how-to-reduce-back-pain-while-pregnant-and-working-from-home\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vitalitycenterjax.com\/how-to-reduce-back-pain-while-pregnant-and-working-from-home\/","url":"https:\/\/vitalitycenterjax.com\/how-to-reduce-back-pain-while-pregnant-and-working-from-home\/","name":"C\u00f3mo reducir el dolor de espalda durante el embarazo y trabajar desde casa - Vitality Center Jacksonville","isPartOf":{"@id":"http:\/\/vitalitycenterjax.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vitalitycenterjax.com\/how-to-reduce-back-pain-while-pregnant-and-working-from-home\/#primaryimage"},"image":{"@id":"https:\/\/vitalitycenterjax.com\/how-to-reduce-back-pain-while-pregnant-and-working-from-home\/#primaryimage"},"thumbnailUrl":"https:\/\/vitalitycenterjax.com\/wp-content\/uploads\/2021\/08\/How-to-Reduce-Back-Pain-While-Pregnant-and-Working-From-Home.jpg","datePublished":"2021-08-31T21:50:12+00:00","dateModified":"2024-04-25T18:56:30+00:00","description":"Para muchas familias embarazadas, la posibilidad de quedarse en casa y al mismo tiempo mantenerse productivos es un punto de inflexi\u00f3n absoluto.","breadcrumb":{"@id":"https:\/\/vitalitycenterjax.com\/how-to-reduce-back-pain-while-pregnant-and-working-from-home\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vitalitycenterjax.com\/how-to-reduce-back-pain-while-pregnant-and-working-from-home\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vitalitycenterjax.com\/how-to-reduce-back-pain-while-pregnant-and-working-from-home\/#primaryimage","url":"https:\/\/vitalitycenterjax.com\/wp-content\/uploads\/2021\/08\/How-to-Reduce-Back-Pain-While-Pregnant-and-Working-From-Home.jpg","contentUrl":"https:\/\/vitalitycenterjax.com\/wp-content\/uploads\/2021\/08\/How-to-Reduce-Back-Pain-While-Pregnant-and-Working-From-Home.jpg","width":936,"height":624},{"@type":"BreadcrumbList","@id":"https:\/\/vitalitycenterjax.com\/how-to-reduce-back-pain-while-pregnant-and-working-from-home\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/vitalitycenterjax.com\/"},{"@type":"ListItem","position":2,"name":"How to Reduce Back Pain While Pregnant and Working From Home"}]},{"@type":"WebSite","@id":"http:\/\/vitalitycenterjax.com\/#website","url":"http:\/\/vitalitycenterjax.com\/","name":"Vitality Center Jacksonville - Espa\u00f1ol","description":"Atenci\u00f3n quiropr\u00e1ctica de calidad y opciones de atenci\u00f3n m\u00e9dica","publisher":{"@id":"http:\/\/vitalitycenterjax.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/vitalitycenterjax.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Organization","Place","MedicalClinic"],"@id":"http:\/\/vitalitycenterjax.com\/#organization","name":"Vitality Center Jacksonville - Espa\u00f1ol","url":"http:\/\/vitalitycenterjax.com\/","logo":{"@id":"https:\/\/vitalitycenterjax.com\/how-to-reduce-back-pain-while-pregnant-and-working-from-home\/#local-main-organization-logo"},"image":{"@id":"https:\/\/vitalitycenterjax.com\/how-to-reduce-back-pain-while-pregnant-and-working-from-home\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/vitalitycenterjax","https:\/\/www.instagram.com\/vitalitycenterjax\/"],"address":{"@id":"https:\/\/vitalitycenterjax.com\/how-to-reduce-back-pain-while-pregnant-and-working-from-home\/#local-main-place-address"},"telephone":["(904) 434-3465"],"contactPoint":{"@type":"ContactPoint","telephone":"(904) 434-3465","email":"frontdesk@vitalitycenterjax.com"},"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Thursday"],"opens":"09:00","closes":"18:30"},{"@type":"OpeningHoursSpecification","dayOfWeek":["Tuesday","Wednesday"],"opens":"08:30","closes":"17:00"},{"@type":"OpeningHoursSpecification","dayOfWeek":["Friday","Saturday","Sunday"],"opens":"00:00","closes":"00:00"}],"email":"frontdesk@vitalitycenterjax.com","areaServed":"Jacksonville","priceRange":"$","currenciesAccepted":"USD"},{"@type":"Person","@id":"http:\/\/vitalitycenterjax.com\/#\/schema\/person\/ebae3caa1942839bfbb345af0ff4509c","name":"juancarlos2023","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/70256e7fa5cde90b9afe5c8505cc59bdcb61e4f24d3c2bd2a6ec18c756d5fff1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/70256e7fa5cde90b9afe5c8505cc59bdcb61e4f24d3c2bd2a6ec18c756d5fff1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/70256e7fa5cde90b9afe5c8505cc59bdcb61e4f24d3c2bd2a6ec18c756d5fff1?s=96&d=mm&r=g","caption":"juancarlos2023"},"url":"https:\/\/vitalitycenterjax.com\/es\/author\/juancarlos2023\/"},{"@type":"PostalAddress","@id":"https:\/\/vitalitycenterjax.com\/how-to-reduce-back-pain-while-pregnant-and-working-from-home\/#local-main-place-address","streetAddress":"3636 University Blvd S Suite B3","addressLocality":"Jacksonville","postalCode":"32216","addressRegion":"FL","addressCountry":"US"},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vitalitycenterjax.com\/how-to-reduce-back-pain-while-pregnant-and-working-from-home\/#local-main-organization-logo","url":"https:\/\/vitalitycenterjax.com\/wp-content\/uploads\/2018\/09\/vfc-circle-e1537364957593.png","contentUrl":"https:\/\/vitalitycenterjax.com\/wp-content\/uploads\/2018\/09\/vfc-circle-e1537364957593.png","width":855,"height":855,"caption":"Vitality Center Jacksonville"}]},"geo.placename":"Jacksonville","geo.region":"United States (US)"},"_links":{"self":[{"href":"https:\/\/vitalitycenterjax.com\/es\/wp-json\/wp\/v2\/posts\/1899","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vitalitycenterjax.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vitalitycenterjax.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vitalitycenterjax.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vitalitycenterjax.com\/es\/wp-json\/wp\/v2\/comments?post=1899"}],"version-history":[{"count":1,"href":"https:\/\/vitalitycenterjax.com\/es\/wp-json\/wp\/v2\/posts\/1899\/revisions"}],"predecessor-version":[{"id":1901,"href":"https:\/\/vitalitycenterjax.com\/es\/wp-json\/wp\/v2\/posts\/1899\/revisions\/1901"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vitalitycenterjax.com\/es\/wp-json\/wp\/v2\/media\/1900"}],"wp:attachment":[{"href":"https:\/\/vitalitycenterjax.com\/es\/wp-json\/wp\/v2\/media?parent=1899"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vitalitycenterjax.com\/es\/wp-json\/wp\/v2\/categories?post=1899"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vitalitycenterjax.com\/es\/wp-json\/wp\/v2\/tags?post=1899"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}